{"id":301375,"date":"2020-04-06T10:00:58","date_gmt":"2020-04-06T08:00:58","guid":{"rendered":"https:\/\/www.elle.be\/fr\/?p=301375"},"modified":"2020-04-03T12:42:53","modified_gmt":"2020-04-03T10:42:53","slug":"horoscope-2020-vos-previsions-du-6-au-12-avril","status":"publish","type":"post","link":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html","title":{"rendered":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez votre horoscope du 6 au 12 avril 2020. avril 2020....","protected":false},"author":6,"featured_media":300614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2191,2216],"tags":[3184],"class_list":["post-301375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-astro","tag-astro"],"acf":[],"image_verticale":"300613","_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.","_yoast_wpseo_focuskw_text_input":null,"_yoast_wpseo_opengraph-title":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be<\/title>\n<meta name=\"description\" content=\"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be\" \/>\n<meta property=\"og:description\" content=\"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\" \/>\n<meta property=\"og:site_name\" content=\"ELLE.be\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ELLEbelgium\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pages\/ELLE-Belgique\/37490723084\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-06T08:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La r\u00e9daction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ELLEBelgique\" \/>\n<meta name=\"twitter:site\" content=\"@ELLEBelgique\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La r\u00e9daction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\"},\"author\":{\"name\":\"La r\u00e9daction\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/person\\\/16ba064c2e0ef434bf6ed0b45c6e813f\"},\"headline\":\"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril\",\"datePublished\":\"2020-04-06T08:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\"},\"wordCount\":1223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/horoscope_fbcover_aries.jpg\",\"keywords\":[\"astro\"],\"articleSection\":[\"Lifestyle\",\"Astro\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\",\"name\":\"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/horoscope_fbcover_aries.jpg\",\"datePublished\":\"2020-04-06T08:00:58+00:00\",\"description\":\"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/horoscope_fbcover_aries.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/horoscope_fbcover_aries.jpg\",\"width\":1200,\"height\":628,\"caption\":\"@ilenia_illustrations\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"FR\",\"item\":\"https:\\\/\\\/www.elle.be\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifestyle\",\"item\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/lifestyle\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/\",\"name\":\"ELLE.be\",\"description\":\"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu&#039;un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\",\"name\":\"ELLE Belgique\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/elle-icon-200px.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/elle-icon-200px.jpeg\",\"width\":200,\"height\":200,\"caption\":\"ELLE Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ELLEbelgium\\\/\",\"https:\\\/\\\/x.com\\\/ELLEBelgique\",\"http:\\\/\\\/instagram.com\\\/ellebelgique\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ellebelgique\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ELLEbelgique1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/person\\\/16ba064c2e0ef434bf6ed0b45c6e813f\",\"name\":\"La r\u00e9daction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cover_FR166-96x96.jpg\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cover_FR166-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cover_FR166-96x96.jpg\",\"caption\":\"La r\u00e9daction\"},\"description\":\"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu'un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.\",\"sameAs\":[\"http:\\\/\\\/www.elle.be\\\/fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pages\\\/ELLE-Belgique\\\/37490723084\",\"http:\\\/\\\/instagram.com\\\/ellebelgique#\",\"http:\\\/\\\/www.pinterest.com\\\/ellebelgique\\\/pins\\\/\",\"https:\\\/\\\/x.com\\\/ELLEBelgique\"],\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/author\\\/elle-be\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be","description":"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html","og_locale":"fr_FR","og_type":"article","og_title":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be","og_description":"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.","og_url":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html","og_site_name":"ELLE.be","article_publisher":"https:\/\/www.facebook.com\/ELLEbelgium\/","article_author":"https:\/\/www.facebook.com\/pages\/ELLE-Belgique\/37490723084","article_published_time":"2020-04-06T08:00:58+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg","type":"image\/jpeg"}],"author":"La r\u00e9daction","twitter_card":"summary_large_image","twitter_creator":"@ELLEBelgique","twitter_site":"@ELLEBelgique","twitter_misc":{"\u00c9crit par":"La r\u00e9daction","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#article","isPartOf":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html"},"author":{"name":"La r\u00e9daction","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/person\/16ba064c2e0ef434bf6ed0b45c6e813f"},"headline":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril","datePublished":"2020-04-06T08:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html"},"wordCount":1223,"commentCount":0,"publisher":{"@id":"https:\/\/www.elle.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg","keywords":["astro"],"articleSection":["Lifestyle","Astro"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html","url":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html","name":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril - ELLE.be","isPartOf":{"@id":"https:\/\/www.elle.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage"},"image":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg","datePublished":"2020-04-06T08:00:58+00:00","description":"Horoscope 2020 : que vous r\u00e9serve votre signe du zodiaque cette semaine ? D\u00e9couvrez les pr\u00e9dictions pour la semaine du 6 au 12 avril.","breadcrumb":{"@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#primaryimage","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2020\/03\/horoscope_fbcover_aries.jpg","width":1200,"height":628,"caption":"@ilenia_illustrations"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elle.be\/fr\/301375-horoscope-2020-vos-previsions-du-6-au-12-avril.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"FR","item":"https:\/\/www.elle.be\/fr"},{"@type":"ListItem","position":2,"name":"Lifestyle","item":"https:\/\/www.elle.be\/fr\/lifestyle"},{"@type":"ListItem","position":3,"name":"Horoscope 2020 : vos pr\u00e9visions du 6 au 12 avril"}]},{"@type":"WebSite","@id":"https:\/\/www.elle.be\/fr\/#website","url":"https:\/\/www.elle.be\/fr\/","name":"ELLE.be","description":"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu&#039;un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.","publisher":{"@id":"https:\/\/www.elle.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elle.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elle.be\/fr\/#organization","name":"ELLE Belgique","url":"https:\/\/www.elle.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/elle-icon-200px.jpeg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/elle-icon-200px.jpeg","width":200,"height":200,"caption":"ELLE Belgique"},"image":{"@id":"https:\/\/www.elle.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ELLEbelgium\/","https:\/\/x.com\/ELLEBelgique","http:\/\/instagram.com\/ellebelgique\/","https:\/\/www.pinterest.com\/ellebelgique\/","https:\/\/www.youtube.com\/user\/ELLEbelgique1"]},{"@type":"Person","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/person\/16ba064c2e0ef434bf6ed0b45c6e813f","name":"La r\u00e9daction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/cover_FR166-96x96.jpg","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/cover_FR166-96x96.jpg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/cover_FR166-96x96.jpg","caption":"La r\u00e9daction"},"description":"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu'un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.","sameAs":["http:\/\/www.elle.be\/fr\/","https:\/\/www.facebook.com\/pages\/ELLE-Belgique\/37490723084","http:\/\/instagram.com\/ellebelgique#","http:\/\/www.pinterest.com\/ellebelgique\/pins\/","https:\/\/x.com\/ELLEBelgique"],"url":"https:\/\/www.elle.be\/fr\/author\/elle-be"}]}},"_links":{"self":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/301375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/comments?post=301375"}],"version-history":[{"count":2,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/301375\/revisions"}],"predecessor-version":[{"id":301377,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/301375\/revisions\/301377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/media\/300614"}],"wp:attachment":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/media?parent=301375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/categories?post=301375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/tags?post=301375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}