{"id":288578,"date":"2024-12-12T13:00:09","date_gmt":"2024-12-12T12:00:09","guid":{"rendered":"https:\/\/www.elle.be\/fr\/?p=288578"},"modified":"2024-12-12T16:37:14","modified_gmt":"2024-12-12T15:37:14","slug":"notre-top-10-des-cadeaux-de-noel-pour-les-kids","status":"publish","type":"post","link":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html","title":{"rendered":"Notre top 10 des cadeaux de No\u00ebl pour les kids"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Le compte \u00e0 rebours est lanc\u00e9 ! Il ne vous reste plus que quelques jours pour trouver les cadeaux de No\u00ebl parfaits pour vos kids. kids....","protected":false},"author":83,"featured_media":412050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_canonical":"","footnotes":""},"categories":[2191,2217],"tags":[1420,569,1134,1135],"class_list":["post-288578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-famille","tag-fetes","tag-noel","tag-enfants","tag-cadeaux"],"acf":{"credits_auteur_initial":"","credits_photographe":"","credits_link":"","credits_galerie":""},"image_verticale":"412051","_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"En manque d'inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !","_yoast_wpseo_focuskw_text_input":null,"_yoast_wpseo_opengraph-title":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be<\/title>\n<meta name=\"description\" content=\"En manque d&#039;inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be\" \/>\n<meta property=\"og:description\" content=\"En manque d&#039;inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\" \/>\n<meta property=\"og:site_name\" content=\"ELLE.be\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ELLEbelgium\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T12:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T15:37:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jessica Fine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ELLEBelgique\" \/>\n<meta name=\"twitter:site\" content=\"@ELLEBelgique\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jessica Fine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\"},\"author\":{\"name\":\"Jessica Fine\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/person\\\/1a86de25644d68095c5a110e36fae9c4\"},\"headline\":\"Notre top 10 des cadeaux de No\u00ebl pour les kids\",\"datePublished\":\"2024-12-12T12:00:09+00:00\",\"dateModified\":\"2024-12-12T15:37:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg\",\"keywords\":[\"f\u00eates\",\"No\u00ebl\",\"Enfants\",\"cadeaux\"],\"articleSection\":[\"Lifestyle\",\"Famille\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\",\"name\":\"Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg\",\"datePublished\":\"2024-12-12T12:00:09+00:00\",\"dateModified\":\"2024-12-12T15:37:14+00:00\",\"description\":\"En manque d'inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg\",\"width\":1200,\"height\":628,\"caption\":\"\u00a9 Annie Spratt - Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"FR\",\"item\":\"https:\\\/\\\/www.elle.be\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifestyle\",\"item\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/lifestyle\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Notre top 10 des cadeaux de No\u00ebl pour les kids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/\",\"name\":\"ELLE.be\",\"description\":\"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu&#039;un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#organization\",\"name\":\"ELLE Belgique\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/elle-icon-200px.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/elle-icon-200px.jpeg\",\"width\":200,\"height\":200,\"caption\":\"ELLE Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ELLEbelgium\\\/\",\"https:\\\/\\\/x.com\\\/ELLEBelgique\",\"http:\\\/\\\/instagram.com\\\/ellebelgique\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/ellebelgique\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ELLEbelgique1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/#\\\/schema\\\/person\\\/1a86de25644d68095c5a110e36fae9c4\",\"name\":\"Jessica Fine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img-5032-9-2-lr-96x96.jpg\",\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img-5032-9-2-lr-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/img-5032-9-2-lr-96x96.jpg\",\"caption\":\"Jessica Fine\"},\"description\":\"Coordinatrice digitale pour ELLE.be, je g\u00e8re et optimise les articles en ligne et je pilote les projets digitaux pour offrir la meilleure exp\u00e9rience aux lecteurs. Mon but ? Assurer des contenus coh\u00e9rents, visibles et percutants. J'\u00e9cris aussi des articles lifestyle, maman et enfants, pour inspirer et accompagner notre communaut\u00e9 au quotidien.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jessica-fine-9b445741\\\/\"],\"url\":\"https:\\\/\\\/www.elle.be\\\/fr\\\/author\\\/jessica\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be","description":"En manque d'inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html","og_locale":"fr_FR","og_type":"article","og_title":"Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be","og_description":"En manque d'inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !","og_url":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html","og_site_name":"ELLE.be","article_publisher":"https:\/\/www.facebook.com\/ELLEbelgium\/","article_published_time":"2024-12-12T12:00:09+00:00","article_modified_time":"2024-12-12T15:37:14+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg","type":"image\/jpeg"}],"author":"Jessica Fine","twitter_card":"summary_large_image","twitter_creator":"@ELLEBelgique","twitter_site":"@ELLEBelgique","twitter_misc":{"\u00c9crit par":"Jessica Fine","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#article","isPartOf":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html"},"author":{"name":"Jessica Fine","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/person\/1a86de25644d68095c5a110e36fae9c4"},"headline":"Notre top 10 des cadeaux de No\u00ebl pour les kids","datePublished":"2024-12-12T12:00:09+00:00","dateModified":"2024-12-12T15:37:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/www.elle.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg","keywords":["f\u00eates","No\u00ebl","Enfants","cadeaux"],"articleSection":["Lifestyle","Famille"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html","url":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html","name":"Notre top 10 des cadeaux de No\u00ebl pour les kids - ELLE.be","isPartOf":{"@id":"https:\/\/www.elle.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage"},"image":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg","datePublished":"2024-12-12T12:00:09+00:00","dateModified":"2024-12-12T15:37:14+00:00","description":"En manque d'inspiration cadeaux de No\u00ebl pour vos kids ? Voici quelques id\u00e9es pour leur faire les plus belles surprises au pied du sapin !","breadcrumb":{"@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#primaryimage","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2022\/12\/h-elle-annie-spratt-p23gjwnauai-unsplash.jpg","width":1200,"height":628,"caption":"\u00a9 Annie Spratt - Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elle.be\/fr\/288578-notre-top-10-des-cadeaux-de-noel-pour-les-kids.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"FR","item":"https:\/\/www.elle.be\/fr"},{"@type":"ListItem","position":2,"name":"Lifestyle","item":"https:\/\/www.elle.be\/fr\/lifestyle"},{"@type":"ListItem","position":3,"name":"Notre top 10 des cadeaux de No\u00ebl pour les kids"}]},{"@type":"WebSite","@id":"https:\/\/www.elle.be\/fr\/#website","url":"https:\/\/www.elle.be\/fr\/","name":"ELLE.be","description":"Toutes les infos mode, beaut\u00e9 et lifestyle les plus pointues ainsi qu&#039;un contenu 100% belge d\u00e9clin\u00e9 \u00e0 360\u00b0sur le site ELLE.be, nos r\u00e9seaux sociaux et notre cha\u00eene Youtube.","publisher":{"@id":"https:\/\/www.elle.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elle.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.elle.be\/fr\/#organization","name":"ELLE Belgique","url":"https:\/\/www.elle.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/elle-icon-200px.jpeg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2017\/03\/elle-icon-200px.jpeg","width":200,"height":200,"caption":"ELLE Belgique"},"image":{"@id":"https:\/\/www.elle.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ELLEbelgium\/","https:\/\/x.com\/ELLEBelgique","http:\/\/instagram.com\/ellebelgique\/","https:\/\/www.pinterest.com\/ellebelgique\/","https:\/\/www.youtube.com\/user\/ELLEbelgique1"]},{"@type":"Person","@id":"https:\/\/www.elle.be\/fr\/#\/schema\/person\/1a86de25644d68095c5a110e36fae9c4","name":"Jessica Fine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2018\/07\/img-5032-9-2-lr-96x96.jpg","url":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2018\/07\/img-5032-9-2-lr-96x96.jpg","contentUrl":"https:\/\/www.elle.be\/fr\/wp-content\/uploads\/2018\/07\/img-5032-9-2-lr-96x96.jpg","caption":"Jessica Fine"},"description":"Coordinatrice digitale pour ELLE.be, je g\u00e8re et optimise les articles en ligne et je pilote les projets digitaux pour offrir la meilleure exp\u00e9rience aux lecteurs. Mon but ? Assurer des contenus coh\u00e9rents, visibles et percutants. J'\u00e9cris aussi des articles lifestyle, maman et enfants, pour inspirer et accompagner notre communaut\u00e9 au quotidien.","sameAs":["https:\/\/www.linkedin.com\/in\/jessica-fine-9b445741\/"],"url":"https:\/\/www.elle.be\/fr\/author\/jessica"}]}},"_links":{"self":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/288578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/comments?post=288578"}],"version-history":[{"count":71,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/288578\/revisions"}],"predecessor-version":[{"id":439318,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/posts\/288578\/revisions\/439318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/media\/412050"}],"wp:attachment":[{"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/media?parent=288578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/categories?post=288578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elle.be\/fr\/wp-json\/wp\/v2\/tags?post=288578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}